{"id":1590,"date":"2016-05-21T14:58:37","date_gmt":"2016-05-21T12:58:37","guid":{"rendered":"http:\/\/hetbestevanparijs.nl\/paris\/?p=1590"},"modified":"2016-07-05T14:18:11","modified_gmt":"2016-07-05T12:18:11","slug":"hotel-des-invalides","status":"publish","type":"post","link":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/","title":{"rendered":"H\u00f4tel des Invalides"},"content":{"rendered":"<p>Het <strong>H\u00f4tel National des Invalides<\/strong> is gelegen in het 7e arrondissement van Parijs. Het werd in 1671 opgericht door Lodewijk XIV, de zonnekoning en\u00a0diende als onderkomen voor oud-soldaten die hulpbehoevend waren geraakt door hun dienst in het leger. <!--more-->De architect was Lib\u00e9ral Bruant. Vanaf de Pont Alexandre III leidt een zeer mooie, reusachtige esplanade van 500 meter lang en 250 meter breed naar het <strong>H\u00f4tel National des Invalides<\/strong>, dat de Cath\u00e9drale de Saint-Louis-des-Invalides en de D\u00f4me des Invalides omvat. Tevens bestaat <strong>Les Invalides<\/strong> uit het <strong>Mus\u00e9e de l&#8217;Arm\u00e9e<\/strong>, het Mus\u00e9e des Plans-Reliefs en het Mus\u00e9e de l&#8217;Ordre de la Lib\u00e9ration.<br \/>\n(Bron: <a href=\"https:\/\/nl.wikipedia.org\/wiki\/H%C3%B4tel_des_Invalides\" target=\"_blank\">Wikipedia<\/a>)<\/p>\n<p><a href=\"http:\/\/www.musee-armee.fr\/en\/english-version.html\" target=\"_blank\">Offici\u00eble website<\/a><\/p>\n<p><strong>Adres<\/strong>:\u00a0129 Rue de Grenelle, 75007 Paris<br \/>\n<strong>Metro<\/strong>: Invalides<br \/>\n<strong>Favoriete route<\/strong> = Metro\u00a0Champs-\u00c9lys\u00e9es &#8211; Clemenceau, Avenue Winston Churchill in, langs Petit en Grand Palais lopen, over &#8216;Pont Alexandre III&#8217; en dan rechtdoor lopen\u00a0over de &#8216;Esplanade des Invalides&#8217;.<\/p>\n[huge_it_maps id=&#8221;78&#8243;]\n","protected":false},"excerpt":{"rendered":"<p>Het H\u00f4tel National des Invalides is gelegen in het 7e arrondissement van Parijs. Het werd in 1671 opgericht door Lodewijk XIV, de zonnekoning en\u00a0diende als onderkomen voor oud-soldaten die hulpbehoevend waren geraakt door hun dienst&hellip;<\/p>\n","protected":false},"author":1,"featured_media":1593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[12],"tags":[97,98,99,102,100],"class_list":["post-1590","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bezienswaardigheden","tag-7e-arr","tag-invalides","tag-metro-invalides","tag-museum","tag-napoleon"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.1.1 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#8902; Het beste van Parijs<\/title>\n<meta name=\"description\" content=\"7e Arr., Invalides, Metro Invalides, Museum, Napoleon, Het beste van Parijs, H\u00f4tel des Invalides, Pont Alexandre III, Mus\u00e9e de l&#039;Arm\u00e9e\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#8902; Het beste van Parijs\" \/>\n<meta property=\"og:description\" content=\"7e Arr., Invalides, Metro Invalides, Museum, Napoleon, Het beste van Parijs, H\u00f4tel des Invalides, Pont Alexandre III, Mus\u00e9e de l&#039;Arm\u00e9e\" \/>\n<meta property=\"og:url\" content=\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\" \/>\n<meta property=\"og:site_name\" content=\"Het beste van Parijs\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-21T12:58:37+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-07-05T12:18:11+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"789\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Geschreven door\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michel\" \/>\n\t<meta name=\"twitter:label2\" content=\"Geschatte leestijd\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#article\",\"isPartOf\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\"},\"author\":{\"name\":\"Michel\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/6d3485c63b3b6f4ad4b893947d88ed60\"},\"headline\":\"H\u00f4tel des Invalides\",\"datePublished\":\"2016-05-21T12:58:37+00:00\",\"dateModified\":\"2016-07-05T12:18:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\"},\"wordCount\":161,\"image\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg\",\"keywords\":[\"7e Arr.\",\"Invalides\",\"Metro Invalides\",\"Museum\",\"Napoleon\"],\"articleSection\":[\"Bezienswaardigheden\"],\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebPage\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\",\"url\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\",\"name\":\"&#8902; Het beste van Parijs\",\"isPartOf\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage\"},\"image\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage\"},\"thumbnailUrl\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg\",\"datePublished\":\"2016-05-21T12:58:37+00:00\",\"dateModified\":\"2016-07-05T12:18:11+00:00\",\"author\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/6d3485c63b3b6f4ad4b893947d88ed60\"},\"description\":\"7e Arr., Invalides, Metro Invalides, Museum, Napoleon, Het beste van Parijs, H\u00f4tel des Invalides, Pont Alexandre III, Mus\u00e9e de l'Arm\u00e9e\",\"breadcrumb\":{\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage\",\"url\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg\",\"contentUrl\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg\",\"width\":789,\"height\":478},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"H\u00f4tel des Invalides\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/#website\",\"url\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/\",\"name\":\"Het beste van Parijs\",\"description\":\"Latitude 48.864716 - Longitude 2.349014\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Person\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/6d3485c63b3b6f4ad4b893947d88ed60\",\"name\":\"Michel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/468ef0edb2873d428c29c5657ab70355bbdf9cfc12282e045e3a4b11f7ed34aa?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/468ef0edb2873d428c29c5657ab70355bbdf9cfc12282e045e3a4b11f7ed34aa?s=96&d=mm&r=g\",\"caption\":\"Michel\"},\"url\":\"http:\/\/hetbestevanparijs.nl\/hbvp\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"&#8902; Het beste van Parijs","description":"7e Arr., Invalides, Metro Invalides, Museum, Napoleon, Het beste van Parijs, H\u00f4tel des Invalides, Pont Alexandre III, Mus\u00e9e de l'Arm\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/","og_locale":"nl_NL","og_type":"article","og_title":"&#8902; Het beste van Parijs","og_description":"7e Arr., Invalides, Metro Invalides, Museum, Napoleon, Het beste van Parijs, H\u00f4tel des Invalides, Pont Alexandre III, Mus\u00e9e de l'Arm\u00e9e","og_url":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/","og_site_name":"Het beste van Parijs","article_published_time":"2016-05-21T12:58:37+00:00","article_modified_time":"2016-07-05T12:18:11+00:00","og_image":[{"width":789,"height":478,"url":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg","type":"image\/jpeg"}],"author":"Michel","twitter_card":"summary_large_image","twitter_misc":{"Geschreven door":"Michel","Geschatte leestijd":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#article","isPartOf":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/"},"author":{"name":"Michel","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/6d3485c63b3b6f4ad4b893947d88ed60"},"headline":"H\u00f4tel des Invalides","datePublished":"2016-05-21T12:58:37+00:00","dateModified":"2016-07-05T12:18:11+00:00","mainEntityOfPage":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/"},"wordCount":161,"image":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage"},"thumbnailUrl":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg","keywords":["7e Arr.","Invalides","Metro Invalides","Museum","Napoleon"],"articleSection":["Bezienswaardigheden"],"inLanguage":"nl-NL"},{"@type":"WebPage","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/","url":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/","name":"&#8902; Het beste van Parijs","isPartOf":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/#website"},"primaryImageOfPage":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage"},"image":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage"},"thumbnailUrl":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg","datePublished":"2016-05-21T12:58:37+00:00","dateModified":"2016-07-05T12:18:11+00:00","author":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/6d3485c63b3b6f4ad4b893947d88ed60"},"description":"7e Arr., Invalides, Metro Invalides, Museum, Napoleon, Het beste van Parijs, H\u00f4tel des Invalides, Pont Alexandre III, Mus\u00e9e de l'Arm\u00e9e","breadcrumb":{"@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/"]}]},{"@type":"ImageObject","inLanguage":"nl-NL","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#primaryimage","url":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg","contentUrl":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg","width":789,"height":478},{"@type":"BreadcrumbList","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/bezienswaardigheden\/hotel-des-invalides\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/hetbestevanparijs.nl\/hbvp\/"},{"@type":"ListItem","position":2,"name":"H\u00f4tel des Invalides"}]},{"@type":"WebSite","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/#website","url":"http:\/\/hetbestevanparijs.nl\/hbvp\/","name":"Het beste van Parijs","description":"Latitude 48.864716 - Longitude 2.349014","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/hetbestevanparijs.nl\/hbvp\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Person","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/6d3485c63b3b6f4ad4b893947d88ed60","name":"Michel","image":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"http:\/\/hetbestevanparijs.nl\/hbvp\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/468ef0edb2873d428c29c5657ab70355bbdf9cfc12282e045e3a4b11f7ed34aa?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/468ef0edb2873d428c29c5657ab70355bbdf9cfc12282e045e3a4b11f7ed34aa?s=96&d=mm&r=g","caption":"Michel"},"url":"http:\/\/hetbestevanparijs.nl\/hbvp\/author\/admin\/"}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-content\/uploads\/2016\/05\/invalides.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p7xzH3-pE","_links":{"self":[{"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/posts\/1590","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/comments?post=1590"}],"version-history":[{"count":4,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/posts\/1590\/revisions"}],"predecessor-version":[{"id":1996,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/posts\/1590\/revisions\/1996"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/media\/1593"}],"wp:attachment":[{"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/media?parent=1590"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/categories?post=1590"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/hetbestevanparijs.nl\/hbvp\/wp-json\/wp\/v2\/tags?post=1590"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}